{"id":9852,"date":"2020-10-01T10:31:22","date_gmt":"2020-10-01T03:31:22","guid":{"rendered":"https:\/\/www.changfi.com\/fix\/?p=9852"},"modified":"2024-12-18T17:19:08","modified_gmt":"2024-12-18T10:19:08","slug":"%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%9b%e0%b8%8e%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%87%e0%b8%b2%e0%b8%99-37100","status":"publish","type":"post","link":"https:\/\/www.changfi.com\/fix\/2020\/10\/01\/%e0%b8%a0%e0%b8%b2%e0%b8%9e%e0%b8%9b%e0%b8%8e%e0%b8%b4%e0%b8%9a%e0%b8%b1%e0%b8%95%e0%b8%b4%e0%b8%87%e0%b8%b2%e0%b8%99-37100\/","title":{"rendered":"\u0e20\u0e32\u0e1e\u0e1b\u0e0e\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19-37(100)"},"content":{"rendered":"\n<!-- Final Tiles Grid Gallery for WordPress v3.6.13 free --><style>#ftg-4343 .tile .icon { color:#ffffff; }#ftg-4343 .ftg-items .loading-bar i { background:#666; }#ftg-4343 .ftg-items .loading-bar { background:#fff; }#ftg-4343 .tile .icon { font-size:12px; }#ftg-4343 .tile .icon { margin: -6px 0 0 -6px; }#ftg-4343 .tile .caption-block .text-wrapper span.text { font-size:12px; }#ftg-4343 .tile .caption-outside .text-wrapper span.text { font-size:12px; }#ftg-4343 .tile .caption-block .text-wrapper span.title { font-size:14px; }#ftg-4343 .tile .caption-outside .text-wrapper span.title { font-size:14px; }#ftg-4343 .tile { background-color: transparent; }#ftg-4343 .tile .caption-block .text-wrapper span.text { color: #ffffff; }#ftg-4343 .tile .caption-block .text-wrapper span.title { color: #ffffff; }#ftg-4343 .tile .caption-outside .text-wrapper span.text { color: #ffffff; }#ftg-4343 .tile .caption-outside .text-wrapper span.title { color: #ffffff; }#ftg-4343 .tile .ftg-social a { color: #ffffff; }#ftg-4343 .tile .caption-block { transition-timing-function:linear; }#ftg-4343 .tile .caption-block { transition-duration:0.25s; }#ftg-4343 .tile .tile-inner:before { background-color: #000000; }#ftg-4343 .tile .tile-inner:before { background-color: rgba(0, 0, 0, 0.8); }<\/style><a name=\"43\"><\/a><div class=\"final-tiles-gallery  ftg-hover-enabled caption-inside  caption-none caption-middle caption-center\" id=\"ftg-4343\" style=\"width: 100%\"><div class='ftg-items'><div class='loading-bar'><i><\/i><\/div><div  class='tile ftg-preload  '><a title=\"81323253_1458716910919213_4668573109371011072_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81323253_1458716910919213_4668573109371011072_o-768x1024.jpg' ><img alt='81323253_1458716910919213_4668573109371011072_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81323253_1458716910919213_4668573109371011072_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81323253_1458716910919213_4668573109371011072_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>81323253_1458716910919213_4668573109371011072_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"81355134_1458716787585892_4474538830673739776_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81355134_1458716787585892_4474538830673739776_o-768x1024.jpg' ><img alt='81355134_1458716787585892_4474538830673739776_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81355134_1458716787585892_4474538830673739776_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81355134_1458716787585892_4474538830673739776_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>81355134_1458716787585892_4474538830673739776_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"81362271_1458716424252595_7689704258437906432_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81362271_1458716424252595_7689704258437906432_o-768x1024.jpg' ><img alt='81362271_1458716424252595_7689704258437906432_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81362271_1458716424252595_7689704258437906432_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81362271_1458716424252595_7689704258437906432_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>81362271_1458716424252595_7689704258437906432_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"81374728_1458717114252526_2434812540581052416_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81374728_1458717114252526_2434812540581052416_o-768x1024.jpg' ><img alt='81374728_1458717114252526_2434812540581052416_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81374728_1458717114252526_2434812540581052416_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81374728_1458717114252526_2434812540581052416_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>81374728_1458717114252526_2434812540581052416_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"81380927_1458715900919314_7133666436404215808_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81380927_1458715900919314_7133666436404215808_o-768x1024.jpg' ><img alt='81380927_1458715900919314_7133666436404215808_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81380927_1458715900919314_7133666436404215808_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81380927_1458715900919314_7133666436404215808_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>81380927_1458715900919314_7133666436404215808_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"81392194_1458717787585792_4136636208556015616_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81392194_1458717787585792_4136636208556015616_o-768x1024.jpg' ><img alt='81392194_1458717787585792_4136636208556015616_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81392194_1458717787585792_4136636208556015616_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81392194_1458717787585792_4136636208556015616_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>81392194_1458717787585792_4136636208556015616_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"81393210_1460510347406536_6989795391449333760_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81393210_1460510347406536_6989795391449333760_o-768x1024.jpg' ><img alt='81393210_1460510347406536_6989795391449333760_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81393210_1460510347406536_6989795391449333760_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81393210_1460510347406536_6989795391449333760_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>81393210_1460510347406536_6989795391449333760_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"81421918_1460510690739835_8933655000723226624_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81421918_1460510690739835_8933655000723226624_o-768x1024.jpg' ><img alt='81421918_1460510690739835_8933655000723226624_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81421918_1460510690739835_8933655000723226624_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81421918_1460510690739835_8933655000723226624_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>81421918_1460510690739835_8933655000723226624_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"81421922_1458715814252656_7063518968941641728_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81421922_1458715814252656_7063518968941641728_o-768x1024.jpg' ><img alt='81421922_1458715814252656_7063518968941641728_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81421922_1458715814252656_7063518968941641728_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81421922_1458715814252656_7063518968941641728_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>81421922_1458715814252656_7063518968941641728_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"81432222_1458717040919200_801929548747767808_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81432222_1458717040919200_801929548747767808_o-768x1024.jpg' ><img alt='81432222_1458717040919200_801929548747767808_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81432222_1458717040919200_801929548747767808_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81432222_1458717040919200_801929548747767808_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>81432222_1458717040919200_801929548747767808_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"81452766_1458717904252447_4482726335420039168_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81452766_1458717904252447_4482726335420039168_o-768x1024.jpg' ><img alt='81452766_1458717904252447_4482726335420039168_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81452766_1458717904252447_4482726335420039168_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81452766_1458717904252447_4482726335420039168_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>81452766_1458717904252447_4482726335420039168_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"81460555_1460510454073192_4117783368005844992_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81460555_1460510454073192_4117783368005844992_o-768x1024.jpg' ><img alt='81460555_1460510454073192_4117783368005844992_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81460555_1460510454073192_4117783368005844992_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81460555_1460510454073192_4117783368005844992_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>81460555_1460510454073192_4117783368005844992_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"81476385_1458715650919339_7890569626784890880_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81476385_1458715650919339_7890569626784890880_o-576x1024.jpg' ><img alt='81476385_1458715650919339_7890569626784890880_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81476385_1458715650919339_7890569626784890880_o-169x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81476385_1458715650919339_7890569626784890880_o-169x300.jpg' width='169' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>81476385_1458715650919339_7890569626784890880_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"81483073_1458716974252540_939905819808366592_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81483073_1458716974252540_939905819808366592_o-768x1024.jpg' ><img alt='81483073_1458716974252540_939905819808366592_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81483073_1458716974252540_939905819808366592_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81483073_1458716974252540_939905819808366592_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>81483073_1458716974252540_939905819808366592_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"81507832_1458716227585948_5605315840384696320_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81507832_1458716227585948_5605315840384696320_o-1024x768.jpg' ><img alt='81507832_1458716227585948_5605315840384696320_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81507832_1458716227585948_5605315840384696320_o-300x225.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81507832_1458716227585948_5605315840384696320_o-300x225.jpg' width='300' height='225' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>81507832_1458716227585948_5605315840384696320_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"81511944_1458716650919239_8743309115385708544_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81511944_1458716650919239_8743309115385708544_o-768x1024.jpg' ><img alt='81511944_1458716650919239_8743309115385708544_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81511944_1458716650919239_8743309115385708544_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81511944_1458716650919239_8743309115385708544_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>81511944_1458716650919239_8743309115385708544_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"81520108_1458717267585844_2968025836956942336_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81520108_1458717267585844_2968025836956942336_o-768x1024.jpg' ><img alt='81520108_1458717267585844_2968025836956942336_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81520108_1458717267585844_2968025836956942336_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81520108_1458717267585844_2968025836956942336_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>81520108_1458717267585844_2968025836956942336_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"81520108_1458717917585779_2786714698794401792_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81520108_1458717917585779_2786714698794401792_o-768x1024.jpg' ><img alt='81520108_1458717917585779_2786714698794401792_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81520108_1458717917585779_2786714698794401792_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81520108_1458717917585779_2786714698794401792_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>81520108_1458717917585779_2786714698794401792_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"81520120_1458715677586003_5560860420610195456_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81520120_1458715677586003_5560860420610195456_o-768x1024.jpg' ><img alt='81520120_1458715677586003_5560860420610195456_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81520120_1458715677586003_5560860420610195456_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81520120_1458715677586003_5560860420610195456_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>81520120_1458715677586003_5560860420610195456_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"81520126_1460510500739854_4997714363277115392_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81520126_1460510500739854_4997714363277115392_o-768x1024.jpg' ><img alt='81520126_1460510500739854_4997714363277115392_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81520126_1460510500739854_4997714363277115392_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81520126_1460510500739854_4997714363277115392_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>81520126_1460510500739854_4997714363277115392_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"81525896_1460508934073344_1198329268954726400_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81525896_1460508934073344_1198329268954726400_o-768x1024.jpg' ><img alt='81525896_1460508934073344_1198329268954726400_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81525896_1460508934073344_1198329268954726400_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81525896_1460508934073344_1198329268954726400_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>81525896_1460508934073344_1198329268954726400_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"81533534_1458715957585975_8092132403331465216_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81533534_1458715957585975_8092132403331465216_o-768x1024.jpg' ><img alt='81533534_1458715957585975_8092132403331465216_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81533534_1458715957585975_8092132403331465216_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81533534_1458715957585975_8092132403331465216_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>81533534_1458715957585975_8092132403331465216_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"81544130_1460509660739938_3126951133126328320_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81544130_1460509660739938_3126951133126328320_o-768x1024.jpg' ><img alt='81544130_1460509660739938_3126951133126328320_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81544130_1460509660739938_3126951133126328320_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81544130_1460509660739938_3126951133126328320_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>81544130_1460509660739938_3126951133126328320_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"81552259_1458716067585964_6819729899301896192_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81552259_1458716067585964_6819729899301896192_o-1024x768.jpg' ><img alt='81552259_1458716067585964_6819729899301896192_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81552259_1458716067585964_6819729899301896192_o-300x225.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81552259_1458716067585964_6819729899301896192_o-300x225.jpg' width='300' height='225' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>81552259_1458716067585964_6819729899301896192_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"81557780_1460510580739846_8606552786835865600_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81557780_1460510580739846_8606552786835865600_o-768x1024.jpg' ><img alt='81557780_1460510580739846_8606552786835865600_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81557780_1460510580739846_8606552786835865600_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81557780_1460510580739846_8606552786835865600_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>81557780_1460510580739846_8606552786835865600_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"81562326_1460509680739936_9114011689778413568_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81562326_1460509680739936_9114011689778413568_o-768x1024.jpg' ><img alt='81562326_1460509680739936_9114011689778413568_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81562326_1460509680739936_9114011689778413568_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81562326_1460509680739936_9114011689778413568_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>81562326_1460509680739936_9114011689778413568_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"81563625_1460510040739900_5816727462272303104_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81563625_1460510040739900_5816727462272303104_o-768x1024.jpg' ><img alt='81563625_1460510040739900_5816727462272303104_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81563625_1460510040739900_5816727462272303104_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81563625_1460510040739900_5816727462272303104_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>81563625_1460510040739900_5816727462272303104_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"81585899_1458715847585986_2005314217548185600_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81585899_1458715847585986_2005314217548185600_o-576x1024.jpg' ><img alt='81585899_1458715847585986_2005314217548185600_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81585899_1458715847585986_2005314217548185600_o-169x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81585899_1458715847585986_2005314217548185600_o-169x300.jpg' width='169' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>81585899_1458715847585986_2005314217548185600_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"81624714_1460509987406572_2500543793820860416_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81624714_1460509987406572_2500543793820860416_o-768x1024.jpg' ><img alt='81624714_1460509987406572_2500543793820860416_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81624714_1460509987406572_2500543793820860416_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81624714_1460509987406572_2500543793820860416_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>81624714_1460509987406572_2500543793820860416_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"81654267_1458715717585999_3441262504909471744_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81654267_1458715717585999_3441262504909471744_o-768x1024.jpg' ><img alt='81654267_1458715717585999_3441262504909471744_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81654267_1458715717585999_3441262504909471744_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81654267_1458715717585999_3441262504909471744_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>81654267_1458715717585999_3441262504909471744_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"81670345_1460509304073307_2210697595137818624_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81670345_1460509304073307_2210697595137818624_o-768x1024.jpg' ><img alt='81670345_1460509304073307_2210697595137818624_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81670345_1460509304073307_2210697595137818624_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81670345_1460509304073307_2210697595137818624_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>81670345_1460509304073307_2210697595137818624_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"81699037_1458716134252624_8530783280197271552_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81699037_1458716134252624_8530783280197271552_o-768x1024.jpg' ><img alt='81699037_1458716134252624_8530783280197271552_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81699037_1458716134252624_8530783280197271552_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81699037_1458716134252624_8530783280197271552_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>81699037_1458716134252624_8530783280197271552_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"81702236_1460509220739982_8537048559445344256_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81702236_1460509220739982_8537048559445344256_o-768x1024.jpg' ><img alt='81702236_1460509220739982_8537048559445344256_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81702236_1460509220739982_8537048559445344256_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81702236_1460509220739982_8537048559445344256_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>81702236_1460509220739982_8537048559445344256_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"81716412_1460508864073351_8201154620517515264_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81716412_1460508864073351_8201154620517515264_o-768x1024.jpg' ><img alt='81716412_1460508864073351_8201154620517515264_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81716412_1460508864073351_8201154620517515264_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81716412_1460508864073351_8201154620517515264_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>81716412_1460508864073351_8201154620517515264_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"81716414_1458716260919278_308673780530544640_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81716414_1458716260919278_308673780530544640_o-768x1024.jpg' ><img alt='81716414_1458716260919278_308673780530544640_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81716414_1458716260919278_308673780530544640_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81716414_1458716260919278_308673780530544640_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>81716414_1458716260919278_308673780530544640_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"81717493_1460509944073243_5882122737400414208_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81717493_1460509944073243_5882122737400414208_o-768x1024.jpg' ><img alt='81717493_1460509944073243_5882122737400414208_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81717493_1460509944073243_5882122737400414208_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81717493_1460509944073243_5882122737400414208_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>81717493_1460509944073243_5882122737400414208_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"81717681_1458716870919217_4663046366929354752_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81717681_1458716870919217_4663046366929354752_o-768x1024.jpg' ><img alt='81717681_1458716870919217_4663046366929354752_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81717681_1458716870919217_4663046366929354752_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81717681_1458716870919217_4663046366929354752_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>81717681_1458716870919217_4663046366929354752_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"81740160_1460512840739620_1696435038796644352_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81740160_1460512840739620_1696435038796644352_o-768x1024.jpg' ><img alt='81740160_1460512840739620_1696435038796644352_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81740160_1460512840739620_1696435038796644352_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81740160_1460512840739620_1696435038796644352_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>81740160_1460512840739620_1696435038796644352_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"81752170_1458716180919286_6087509087107416064_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81752170_1458716180919286_6087509087107416064_o-576x1024.jpg' ><img alt='81752170_1458716180919286_6087509087107416064_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81752170_1458716180919286_6087509087107416064_o-169x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81752170_1458716180919286_6087509087107416064_o-169x300.jpg' width='169' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>81752170_1458716180919286_6087509087107416064_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"81752255_1458716290919275_66511283725271040_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81752255_1458716290919275_66511283725271040_o-768x1024.jpg' ><img alt='81752255_1458716290919275_66511283725271040_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81752255_1458716290919275_66511283725271040_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81752255_1458716290919275_66511283725271040_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>81752255_1458716290919275_66511283725271040_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"81845954_1458716794252558_6554100134982975488_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81845954_1458716794252558_6554100134982975488_o-768x1024.jpg' ><img alt='81845954_1458716794252558_6554100134982975488_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81845954_1458716794252558_6554100134982975488_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81845954_1458716794252558_6554100134982975488_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>81845954_1458716794252558_6554100134982975488_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"81860982_1460510420739862_1830508249737068544_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81860982_1460510420739862_1830508249737068544_o-768x1024.jpg' ><img alt='81860982_1460510420739862_1830508249737068544_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81860982_1460510420739862_1830508249737068544_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81860982_1460510420739862_1830508249737068544_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>81860982_1460510420739862_1830508249737068544_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"81860982_1460510840739820_1451291576989908992_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81860982_1460510840739820_1451291576989908992_o-768x1024.jpg' ><img alt='81860982_1460510840739820_1451291576989908992_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81860982_1460510840739820_1451291576989908992_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81860982_1460510840739820_1451291576989908992_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>81860982_1460510840739820_1451291576989908992_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"81862960_1460511487406422_7971993788581150720_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81862960_1460511487406422_7971993788581150720_o-579x1024.jpg' ><img alt='81862960_1460511487406422_7971993788581150720_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81862960_1460511487406422_7971993788581150720_o-170x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81862960_1460511487406422_7971993788581150720_o-170x300.jpg' width='170' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>81862960_1460511487406422_7971993788581150720_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"81880407_1460509530739951_4898192433361190912_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81880407_1460509530739951_4898192433361190912_o-768x1024.jpg' ><img alt='81880407_1460509530739951_4898192433361190912_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81880407_1460509530739951_4898192433361190912_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81880407_1460509530739951_4898192433361190912_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>81880407_1460509530739951_4898192433361190912_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"81880509_1458717480919156_5726721723890401280_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81880509_1458717480919156_5726721723890401280_o-768x1024.jpg' ><img alt='81880509_1458717480919156_5726721723890401280_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81880509_1458717480919156_5726721723890401280_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81880509_1458717480919156_5726721723890401280_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>81880509_1458717480919156_5726721723890401280_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"81880514_1458716310919273_4008863366746472448_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81880514_1458716310919273_4008863366746472448_o-768x1024.jpg' ><img alt='81880514_1458716310919273_4008863366746472448_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81880514_1458716310919273_4008863366746472448_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81880514_1458716310919273_4008863366746472448_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>81880514_1458716310919273_4008863366746472448_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"81907525_1460512027406368_8913318605454573568_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81907525_1460512027406368_8913318605454573568_o-768x1024.jpg' ><img alt='81907525_1460512027406368_8913318605454573568_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81907525_1460512027406368_8913318605454573568_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81907525_1460512027406368_8913318605454573568_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>81907525_1460512027406368_8913318605454573568_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"81913237_1460512944072943_5137495779027451904_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81913237_1460512944072943_5137495779027451904_o-768x1024.jpg' ><img alt='81913237_1460512944072943_5137495779027451904_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81913237_1460512944072943_5137495779027451904_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81913237_1460512944072943_5137495779027451904_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>81913237_1460512944072943_5137495779027451904_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"81920918_1460511624073075_3613473556559560704_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81920918_1460511624073075_3613473556559560704_o-579x1024.jpg' ><img alt='81920918_1460511624073075_3613473556559560704_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81920918_1460511624073075_3613473556559560704_o-170x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81920918_1460511624073075_3613473556559560704_o-170x300.jpg' width='170' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>81920918_1460511624073075_3613473556559560704_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"81947265_1458717417585829_2917085720940118016_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81947265_1458717417585829_2917085720940118016_o-768x1024.jpg' ><img alt='81947265_1458717417585829_2917085720940118016_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81947265_1458717417585829_2917085720940118016_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81947265_1458717417585829_2917085720940118016_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>81947265_1458717417585829_2917085720940118016_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"81949177_1460512700739634_4499488781027508224_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81949177_1460512700739634_4499488781027508224_o-579x1024.jpg' ><img alt='81949177_1460512700739634_4499488781027508224_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81949177_1460512700739634_4499488781027508224_o-170x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81949177_1460512700739634_4499488781027508224_o-170x300.jpg' width='170' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>81949177_1460512700739634_4499488781027508224_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"81986149_1458716444252593_7717130592445267968_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81986149_1458716444252593_7717130592445267968_o-768x1024.jpg' ><img alt='81986149_1458716444252593_7717130592445267968_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81986149_1458716444252593_7717130592445267968_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/81986149_1458716444252593_7717130592445267968_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>81986149_1458716444252593_7717130592445267968_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"82004579_1458716764252561_3859631167519064064_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82004579_1458716764252561_3859631167519064064_o-768x1024.jpg' ><img alt='82004579_1458716764252561_3859631167519064064_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82004579_1458716764252561_3859631167519064064_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82004579_1458716764252561_3859631167519064064_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>82004579_1458716764252561_3859631167519064064_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"82007444_1460509277406643_1572137177716883456_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82007444_1460509277406643_1572137177716883456_o-768x1024.jpg' ><img alt='82007444_1460509277406643_1572137177716883456_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82007444_1460509277406643_1572137177716883456_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82007444_1460509277406643_1572137177716883456_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>82007444_1460509277406643_1572137177716883456_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"82007447_1458717977585773_9127658514569756672_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82007447_1458717977585773_9127658514569756672_o-768x1024.jpg' ><img alt='82007447_1458717977585773_9127658514569756672_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82007447_1458717977585773_9127658514569756672_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82007447_1458717977585773_9127658514569756672_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>82007447_1458717977585773_9127658514569756672_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"82019053_1460509830739921_6851785563809251328_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82019053_1460509830739921_6851785563809251328_o-768x1024.jpg' ><img alt='82019053_1460509830739921_6851785563809251328_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82019053_1460509830739921_6851785563809251328_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82019053_1460509830739921_6851785563809251328_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>82019053_1460509830739921_6851785563809251328_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"82026666_1458717824252455_6824834515177832448_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82026666_1458717824252455_6824834515177832448_o-768x1024.jpg' ><img alt='82026666_1458717824252455_6824834515177832448_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82026666_1458717824252455_6824834515177832448_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82026666_1458717824252455_6824834515177832448_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>82026666_1458717824252455_6824834515177832448_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"82034965_1458716667585904_366056772693131264_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82034965_1458716667585904_366056772693131264_o-768x1024.jpg' ><img alt='82034965_1458716667585904_366056772693131264_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82034965_1458716667585904_366056772693131264_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82034965_1458716667585904_366056772693131264_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>82034965_1458716667585904_366056772693131264_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"82042252_1460510107406560_8980786472885944320_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82042252_1460510107406560_8980786472885944320_o-768x1024.jpg' ><img alt='82042252_1460510107406560_8980786472885944320_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82042252_1460510107406560_8980786472885944320_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82042252_1460510107406560_8980786472885944320_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>82042252_1460510107406560_8980786472885944320_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"82053686_1460511287406442_6102032832551452672_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82053686_1460511287406442_6102032832551452672_o-768x1024.jpg' ><img alt='82053686_1460511287406442_6102032832551452672_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82053686_1460511287406442_6102032832551452672_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82053686_1460511287406442_6102032832551452672_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>82053686_1460511287406442_6102032832551452672_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"82056198_1458715930919311_5010445346422128640_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82056198_1458715930919311_5010445346422128640_o-768x1024.jpg' ><img alt='82056198_1458715930919311_5010445346422128640_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82056198_1458715930919311_5010445346422128640_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82056198_1458715930919311_5010445346422128640_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>82056198_1458715930919311_5010445346422128640_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"82057572_1460509400739964_5441122869905981440_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82057572_1460509400739964_5441122869905981440_o-768x1024.jpg' ><img alt='82057572_1460509400739964_5441122869905981440_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82057572_1460509400739964_5441122869905981440_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82057572_1460509400739964_5441122869905981440_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>82057572_1460509400739964_5441122869905981440_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"82075741_1460511234073114_3399204879476981760_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82075741_1460511234073114_3399204879476981760_o-768x1024.jpg' ><img alt='82075741_1460511234073114_3399204879476981760_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82075741_1460511234073114_3399204879476981760_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82075741_1460511234073114_3399204879476981760_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>82075741_1460511234073114_3399204879476981760_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"82079945_1458715607586010_429734756687544320_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82079945_1458715607586010_429734756687544320_o-768x1024.jpg' ><img alt='82079945_1458715607586010_429734756687544320_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82079945_1458715607586010_429734756687544320_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82079945_1458715607586010_429734756687544320_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>82079945_1458715607586010_429734756687544320_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"82085568_1460511030739801_359207438022344704_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82085568_1460511030739801_359207438022344704_o-768x1024.jpg' ><img alt='82085568_1460511030739801_359207438022344704_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82085568_1460511030739801_359207438022344704_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82085568_1460511030739801_359207438022344704_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>82085568_1460511030739801_359207438022344704_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"82087838_1458717860919118_8060305153774845952_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82087838_1458717860919118_8060305153774845952_o-768x1024.jpg' ><img alt='82087838_1458717860919118_8060305153774845952_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82087838_1458717860919118_8060305153774845952_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82087838_1458717860919118_8060305153774845952_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>82087838_1458717860919118_8060305153774845952_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"82092719_1460511144073123_7318062928748347392_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82092719_1460511144073123_7318062928748347392_o-768x1024.jpg' ><img alt='82092719_1460511144073123_7318062928748347392_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82092719_1460511144073123_7318062928748347392_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82092719_1460511144073123_7318062928748347392_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>82092719_1460511144073123_7318062928748347392_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"82099291_1458717314252506_6698939415890231296_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82099291_1458717314252506_6698939415890231296_o-768x1024.jpg' ><img alt='82099291_1458717314252506_6698939415890231296_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82099291_1458717314252506_6698939415890231296_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82099291_1458717314252506_6698939415890231296_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>82099291_1458717314252506_6698939415890231296_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"82106523_1460509057406665_5973827255606968320_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82106523_1460509057406665_5973827255606968320_o-768x1024.jpg' ><img alt='82106523_1460509057406665_5973827255606968320_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82106523_1460509057406665_5973827255606968320_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82106523_1460509057406665_5973827255606968320_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>82106523_1460509057406665_5973827255606968320_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"82110222_1460509334073304_3510947181055967232_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82110222_1460509334073304_3510947181055967232_o-768x1024.jpg' ><img alt='82110222_1460509334073304_3510947181055967232_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82110222_1460509334073304_3510947181055967232_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82110222_1460509334073304_3510947181055967232_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>82110222_1460509334073304_3510947181055967232_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"82120937_1460509010740003_6370966234174849024_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82120937_1460509010740003_6370966234174849024_o-1024x768.jpg' ><img alt='82120937_1460509010740003_6370966234174849024_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82120937_1460509010740003_6370966234174849024_o-300x225.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82120937_1460509010740003_6370966234174849024_o-300x225.jpg' width='300' height='225' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>82120937_1460509010740003_6370966234174849024_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"82125349_1460509800739924_3514142924487000064_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82125349_1460509800739924_3514142924487000064_o-768x1024.jpg' ><img alt='82125349_1460509800739924_3514142924487000064_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82125349_1460509800739924_3514142924487000064_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82125349_1460509800739924_3514142924487000064_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>82125349_1460509800739924_3514142924487000064_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"82146153_1458716710919233_755432151196893184_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82146153_1458716710919233_755432151196893184_o-768x1024.jpg' ><img alt='82146153_1458716710919233_755432151196893184_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82146153_1458716710919233_755432151196893184_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82146153_1458716710919233_755432151196893184_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>82146153_1458716710919233_755432151196893184_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"82151953_1460511580739746_6985648067949101056_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82151953_1460511580739746_6985648067949101056_o-579x1024.jpg' ><img alt='82151953_1460511580739746_6985648067949101056_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82151953_1460511580739746_6985648067949101056_o-170x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82151953_1460511580739746_6985648067949101056_o-170x300.jpg' width='170' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>82151953_1460511580739746_6985648067949101056_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"82199424_1458716997585871_8083931257769033728_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82199424_1458716997585871_8083931257769033728_o-768x1024.jpg' ><img alt='82199424_1458716997585871_8083931257769033728_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82199424_1458716997585871_8083931257769033728_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82199424_1458716997585871_8083931257769033728_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>82199424_1458716997585871_8083931257769033728_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"82215625_1460510974073140_5824090281758162944_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82215625_1460510974073140_5824090281758162944_o-768x1024.jpg' ><img alt='82215625_1460510974073140_5824090281758162944_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82215625_1460510974073140_5824090281758162944_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82215625_1460510974073140_5824090281758162944_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>82215625_1460510974073140_5824090281758162944_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"82223867_1460512907406280_6355450110767267840_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82223867_1460512907406280_6355450110767267840_o-768x1024.jpg' ><img alt='82223867_1460512907406280_6355450110767267840_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82223867_1460512907406280_6355450110767267840_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82223867_1460512907406280_6355450110767267840_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>82223867_1460512907406280_6355450110767267840_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"82231091_1460510604073177_6097571306423713792_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82231091_1460510604073177_6097571306423713792_o-768x1024.jpg' ><img alt='82231091_1460510604073177_6097571306423713792_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82231091_1460510604073177_6097571306423713792_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82231091_1460510604073177_6097571306423713792_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>82231091_1460510604073177_6097571306423713792_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"82258012_1460509564073281_2222054918892552192_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82258012_1460509564073281_2222054918892552192_o-768x1024.jpg' ><img alt='82258012_1460509564073281_2222054918892552192_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82258012_1460509564073281_2222054918892552192_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82258012_1460509564073281_2222054918892552192_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>82258012_1460509564073281_2222054918892552192_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"82259528_1458716574252580_7750345949662150656_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82259528_1458716574252580_7750345949662150656_o-768x1024.jpg' ><img alt='82259528_1458716574252580_7750345949662150656_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82259528_1458716574252580_7750345949662150656_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82259528_1458716574252580_7750345949662150656_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>82259528_1458716574252580_7750345949662150656_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"82282305_1458716477585923_6491833451472224256_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82282305_1458716477585923_6491833451472224256_o-768x1024.jpg' ><img alt='82282305_1458716477585923_6491833451472224256_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82282305_1458716477585923_6491833451472224256_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82282305_1458716477585923_6491833451472224256_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>82282305_1458716477585923_6491833451472224256_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"82315445_1460510014073236_6400870309045469184_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82315445_1460510014073236_6400870309045469184_o-768x1024.jpg' ><img alt='82315445_1460510014073236_6400870309045469184_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82315445_1460510014073236_6400870309045469184_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82315445_1460510014073236_6400870309045469184_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>82315445_1460510014073236_6400870309045469184_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"82345152_1460512387406332_2039270907595194368_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82345152_1460512387406332_2039270907595194368_o-768x1024.jpg' ><img alt='82345152_1460512387406332_2039270907595194368_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82345152_1460512387406332_2039270907595194368_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82345152_1460512387406332_2039270907595194368_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>82345152_1460512387406332_2039270907595194368_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"82348713_1460510547406516_7794627818398154752_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82348713_1460510547406516_7794627818398154752_o-768x1024.jpg' ><img alt='82348713_1460510547406516_7794627818398154752_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82348713_1460510547406516_7794627818398154752_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82348713_1460510547406516_7794627818398154752_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>82348713_1460510547406516_7794627818398154752_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"82360175_1460511744073063_7410956431341387776_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82360175_1460511744073063_7410956431341387776_o-579x1024.jpg' ><img alt='82360175_1460511744073063_7410956431341387776_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82360175_1460511744073063_7410956431341387776_o-170x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82360175_1460511744073063_7410956431341387776_o-170x300.jpg' width='170' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>82360175_1460511744073063_7410956431341387776_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"82393737_1460513007406270_6604720911591407616_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82393737_1460513007406270_6604720911591407616_o-576x1024.jpg' ><img alt='82393737_1460513007406270_6604720911591407616_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82393737_1460513007406270_6604720911591407616_o-169x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82393737_1460513007406270_6604720911591407616_o-169x300.jpg' width='169' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>82393737_1460513007406270_6604720911591407616_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"82435361_1460511494073088_3619481597331374080_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82435361_1460511494073088_3619481597331374080_o-579x1024.jpg' ><img alt='82435361_1460511494073088_3619481597331374080_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82435361_1460511494073088_3619481597331374080_o-170x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82435361_1460511494073088_3619481597331374080_o-170x300.jpg' width='170' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>82435361_1460511494073088_3619481597331374080_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"82438030_1458716557585915_1011660584292188160_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82438030_1458716557585915_1011660584292188160_o-768x1024.jpg' ><img alt='82438030_1458716557585915_1011660584292188160_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82438030_1458716557585915_1011660584292188160_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82438030_1458716557585915_1011660584292188160_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>82438030_1458716557585915_1011660584292188160_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"82458107_1460510270739877_912972947478544384_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82458107_1460510270739877_912972947478544384_o-768x1024.jpg' ><img alt='82458107_1460510270739877_912972947478544384_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82458107_1460510270739877_912972947478544384_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82458107_1460510270739877_912972947478544384_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>82458107_1460510270739877_912972947478544384_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"82470773_1460509507406620_8792627262773002240_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82470773_1460509507406620_8792627262773002240_o-768x1024.jpg' ><img alt='82470773_1460509507406620_8792627262773002240_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82470773_1460509507406620_8792627262773002240_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82470773_1460509507406620_8792627262773002240_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>82470773_1460509507406620_8792627262773002240_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"82470822_1460509454073292_7832566883726393344_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82470822_1460509454073292_7832566883726393344_o-768x1024.jpg' ><img alt='82470822_1460509454073292_7832566883726393344_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82470822_1460509454073292_7832566883726393344_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82470822_1460509454073292_7832566883726393344_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>82470822_1460509454073292_7832566883726393344_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"82490290_1460509180739986_3562460056731516928_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82490290_1460509180739986_3562460056731516928_o-768x1024.jpg' ><img alt='82490290_1460509180739986_3562460056731516928_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82490290_1460509180739986_3562460056731516928_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82490290_1460509180739986_3562460056731516928_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>82490290_1460509180739986_3562460056731516928_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"82529305_1458717227585848_6890046279238287360_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82529305_1458717227585848_6890046279238287360_o-768x1024.jpg' ><img alt='82529305_1458717227585848_6890046279238287360_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82529305_1458717227585848_6890046279238287360_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82529305_1458717227585848_6890046279238287360_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>82529305_1458717227585848_6890046279238287360_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"82565175_1460511907406380_2653490435384672256_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82565175_1460511907406380_2653490435384672256_o-768x1024.jpg' ><img alt='82565175_1460511907406380_2653490435384672256_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82565175_1460511907406380_2653490435384672256_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82565175_1460511907406380_2653490435384672256_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>82565175_1460511907406380_2653490435384672256_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"82594767_1460508877406683_8713840236666290176_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82594767_1460508877406683_8713840236666290176_o-768x1024.jpg' ><img alt='82594767_1460508877406683_8713840236666290176_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82594767_1460508877406683_8713840236666290176_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82594767_1460508877406683_8713840236666290176_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>82594767_1460508877406683_8713840236666290176_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"82600318_1458717354252502_39828649075015680_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82600318_1458717354252502_39828649075015680_o-1024x768.jpg' ><img alt='82600318_1458717354252502_39828649075015680_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82600318_1458717354252502_39828649075015680_o-300x225.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82600318_1458717354252502_39828649075015680_o-300x225.jpg' width='300' height='225' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>82600318_1458717354252502_39828649075015680_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"82615302_1460510234073214_8905206193916477440_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82615302_1460510234073214_8905206193916477440_o-768x1024.jpg' ><img alt='82615302_1460510234073214_8905206193916477440_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82615302_1460510234073214_8905206193916477440_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82615302_1460510234073214_8905206193916477440_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>82615302_1460510234073214_8905206193916477440_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"82741112_1458717254252512_5370219002868006912_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82741112_1458717254252512_5370219002868006912_o-768x1024.jpg' ><img alt='82741112_1458717254252512_5370219002868006912_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82741112_1458717254252512_5370219002868006912_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82741112_1458717254252512_5370219002868006912_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>82741112_1458717254252512_5370219002868006912_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><div  class='tile ftg-preload  '><a title=\"82852269_1460508980740006_7543790037410775040_o\" data-lightbox='ftg-4343' rel='ftg-4343'  class=' tile-inner  ftg-lightbox' href='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82852269_1460508980740006_7543790037410775040_o-768x1024.jpg' ><img alt='82852269_1460508980740006_7543790037410775040_o' class='item skip-lazy' data-class='item' data-ftg-source='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82852269_1460508980740006_7543790037410775040_o-225x300.jpg' src='https:\/\/www.changfi.com\/fix\/wp-content\/uploads\/2020\/10\/82852269_1460508980740006_7543790037410775040_o-225x300.jpg' width='225' height='300' \/><span class='icon fa fa-zoom'><\/span><div class='caption-block'><div class='text-wrapper'><span class='title'>82852269_1460508980740006_7543790037410775040_o<\/span><\/div><\/div><\/a><div class='ftg-social'><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[71],"tags":[],"class_list":["post-9852","post","type-post","status-publish","format-standard","hentry","category-electric_working"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.changfi.com\/fix\/wp-json\/wp\/v2\/posts\/9852","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.changfi.com\/fix\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.changfi.com\/fix\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.changfi.com\/fix\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.changfi.com\/fix\/wp-json\/wp\/v2\/comments?post=9852"}],"version-history":[{"count":1,"href":"https:\/\/www.changfi.com\/fix\/wp-json\/wp\/v2\/posts\/9852\/revisions"}],"predecessor-version":[{"id":9853,"href":"https:\/\/www.changfi.com\/fix\/wp-json\/wp\/v2\/posts\/9852\/revisions\/9853"}],"wp:attachment":[{"href":"https:\/\/www.changfi.com\/fix\/wp-json\/wp\/v2\/media?parent=9852"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.changfi.com\/fix\/wp-json\/wp\/v2\/categories?post=9852"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.changfi.com\/fix\/wp-json\/wp\/v2\/tags?post=9852"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}